{"id":8244,"count":1,"description":"","link":"https:\/\/aipcf.net\/revue\/en\/descriptores\/homosexuality\/","name":"homosexuality","slug":"homosexuality","taxonomy":"descriptores","meta":[],"_links":{"self":[{"href":"https:\/\/aipcf.net\/revue\/wp-json\/wp\/v2\/descriptores\/8244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aipcf.net\/revue\/wp-json\/wp\/v2\/descriptores"}],"about":[{"href":"https:\/\/aipcf.net\/revue\/wp-json\/wp\/v2\/taxonomies\/descriptores"}],"wp:post_type":[{"href":"https:\/\/aipcf.net\/revue\/wp-json\/wp\/v2\/articulos_revista?descriptores=8244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}